{"id":315,"date":"2024-07-09T11:15:12","date_gmt":"2024-07-09T09:15:12","guid":{"rendered":"https:\/\/www.sole.srl\/it\/?post_type=product&#038;p=315"},"modified":"2024-07-09T11:35:34","modified_gmt":"2024-07-09T09:35:34","slug":"gancio-per-tetto","status":"publish","type":"product","link":"https:\/\/www.sole.srl\/it\/product\/gancio-per-tetto\/","title":{"rendered":"Gancio per tetto"},"content":{"rendered":"<p>Il gancio per tetto ancora il profilo alle travi del tetto tramite una piastra forata e apposite viti (non incluse)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il gancio per tetto ancora il profilo alle travi del tetto tramite una piastra forata e apposite viti (non incluse)<\/p>\n","protected":false},"featured_media":317,"comment_status":"open","ping_status":"closed","template":"","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[17],"product_tag":[],"class_list":["post-315","product","type-product","status-publish","has-post-thumbnail","product_cat-accessori-di-ancoraggio","first","instock","taxable","shipping-taxable","product-type-simple","entry","content-bg","loop-entry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sole.srl\/it\/wp-json\/wp\/v2\/product\/315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sole.srl\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.sole.srl\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sole.srl\/it\/wp-json\/wp\/v2\/comments?post=315"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sole.srl\/it\/wp-json\/wp\/v2\/media\/317"}],"wp:attachment":[{"href":"https:\/\/www.sole.srl\/it\/wp-json\/wp\/v2\/media?parent=315"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.sole.srl\/it\/wp-json\/wp\/v2\/product_brand?post=315"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.sole.srl\/it\/wp-json\/wp\/v2\/product_cat?post=315"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.sole.srl\/it\/wp-json\/wp\/v2\/product_tag?post=315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}